{"id":19158,"date":"2019-11-11T11:33:07","date_gmt":"2019-11-11T10:33:07","guid":{"rendered":"https:\/\/www.myweedo.de\/gruene-seiten\/?p=19158"},"modified":"2019-11-11T13:52:04","modified_gmt":"2019-11-11T12:52:04","slug":"drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an","status":"publish","type":"post","link":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/","title":{"rendered":"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiterhin an"},"content":{"rendered":"\n<p><strong>Berlin: Vergangenen&nbsp;Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung,&nbsp;Daniela Ludwig (CSU), den&nbsp;<\/strong><a href=\"https:\/\/www.bundesregierung.de\/breg-de\/aktuelles\/drogenbericht-1688670\"><strong>Drogen- und Suchtbericht 2019<\/strong><\/a><strong> vor. Der Bericht bietet einen \u00dcberblick \u00fcber aktuelle Statistiken und Trends im Zusammenhang mit dem Konsum von legalen sowie illegalen Drogen innerhalb Deutschlands. Neben Cannabis, Alkohol und Tabak erscheint auch eine unerwartete neue Sucht, von der immer mehr Jugendliche betroffen sind.<\/strong><\/p>\n\n\n\n<h2><strong>R\u00fcckbildung des Alkoholkonsums<\/strong><\/h2>\n\n\n\n<p>Deutschland z\u00e4hlt, neben Russland, Polen und weiteren, weltweit zu den L\u00e4ndern mit dem h\u00f6chsten Alkoholkonsum pro Kopf. Allerdings bildet sich der allgemeine Alkoholkonsum langsam zur\u00fcck.\u00a02004 tranken 21,2 Prozent der Jugendlichen von zw\u00f6lf bis 17 Jahren mindestens einmal in der Woche Alkohol, im vergangenen Jahr waren es hingegen nur noch 8,7 Prozent.\u00a0Vor allem bei Jugendlichen ist also der <strong>regelm\u00e4\u00dfige<\/strong> Konsum in den letzten 15 Jahren erheblich gesunken. Laut Bericht trinken M\u00e4nner weiterhin mehr Alkohol als Frauen.\u00a0In\u00a0Hinblick auf den ebenfalls sinkenden <strong>\u00fcberm\u00e4\u00dfigen<\/strong> Alkoholkonsum sieht dies jedoch anders aus: Beide Geschlechter trinken in diesem Fall ungef\u00e4hr die gleiche Menge. Trotz dieser allgemein erfreulichen Zahlen muss erw\u00e4hnt werden, dass dennoch\u00a0drei Millionen Kinder innerhalb Deutschlands mit mindestens einem alkoholabh\u00e4ngigen Elternteil aufwachsen. Hierbei m\u00fcssen, so Ludwig, bessere Hilfen und Pr\u00e4ventionen angeboten werden, da den Kindern sonst ein hohes Risiko droht, selbst abh\u00e4ngig zu werden.\u00a0<\/p>\n\n\n\n\n\t\t\t<!-- START hempcrew REVOLUTION SLIDER 6.5.6 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_13_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;max-width:;\">\n\t\t\t\t<rs-module id=\"rev_slider_13_1\" style=\"\" data-version=\"6.5.6\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-62\" data-title=\"Slide\" data-link=\" \/\/hempcrew.de\/produkte\/cbd-oele\/?utm_source=weedomagazin&utm_medium=slider&utm_campaign=cbdoele\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Werbebanner-CBD-\u00d6le\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-CBD-Oele.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_13_1',rl:[1240,1024,778,480],el:[600],gw:[1240],gh:[600],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider131\"]!==undefined) {window.RS_MODULES.modules[\"revslider131\"].once = false;window.revapi13 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<h2><strong>Verbot der Tabakwerbung<\/strong><\/h2>\n\n\n\n<p>Eine weitere erfreuliche Nachricht ist, dass neben dem Alkohol- auch der Zigarettenkonsum sinkt.&nbsp;Wiederum ist besonders bei den Jugendlichen ein R\u00fcckgang bemerkbar; die Zahl der rauchenden Jugendlichen hat sich im Vergleich zu den um zwei Drittel verringert. Bei den Erwachsenen liegt der Raucheranteil momentan bei 28 Prozent und reduziert sich ebenfalls weiterhin.&nbsp;Allerdings bedeutet das nicht, dass auf das Inhalieren von Stoffen verzichtet wird. Die meisten, vor allem Jugendliche und junge Erwachsene, h\u00f6ren nicht komplett auf, sondern steigen auf E-Zigaretten und Vaper um. Ludwig warnt vor dem neuen Trend: &#8222;Die E-Zigarette ist kein Wellnessprodukt. Uns fehlen jegliche Langzeitstudien \u00fcber ihre Auswirkungen auf die Gesundheit.\u201c Trotz des vermehrten Umstiegs sterben j\u00e4hrlich 120.000 Menschen in Deutschland an den Folgen des Tabakkonsums. Aufgrund dessen spricht sich die Drogenbeauftragte f\u00fcr ein komplettes Werbeverbot f\u00fcr Tabak sowie E-Zigaretten aus. Werbung f\u00fcr E-Zigaretten m\u00fcssen laut ihr ebenfalls verboten werden, da den Konzernen sonst dadurch eine M\u00f6glichkeit gegeben wird, die Jugendlichen zu erreichen. &#8222;Dann werden wir feststellen, dass es k\u00fcnftig nur noch Werbung f\u00fcr E-Zigaretten geben wird und die wird wiederum genau an den Standorten stattfinden, an denen Jugendliche sich aufhalten: an Bushaltestellen, vor den Kinos, im Internet, in den sozialen Medien. Und das will ich schlicht und ergreifend nicht.&#8220;<\/p>\n\n\n\n<h2><strong>Social Media<\/strong><\/h2>\n\n\n\n<p>Zur \u00dcberraschung einiger wurde auch das Internet, genauer Social Media, in dem Bericht aufgenommen. Immer mehr Jugendliche entwickeln, laut Bericht, eine Internetsucht oder internetbezogene St\u00f6rungen. Momentan nutzen 85% der 12- bis 17-j\u00e4hrigen t\u00e4glich soziale Medien, sch\u00e4tzungsweise 270.000 derselben Altersklasse gelten als abh\u00e4ngig.&nbsp;<\/p>\n\n\n\n<p>   <\/p>\n\n\n\n\n\t\t\t<!-- START Phenopen REVOLUTION SLIDER 6.5.6 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_12_2_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:20;margin-bottom:20;max-width:;\">\n\t\t\t\t<rs-module id=\"rev_slider_12_2\" style=\"\" data-version=\"6.5.6\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-171\" data-title=\"Slide\" data-link=\"\/\/holy-hemp.de?utm_source=weedomagazin&utm_medium=banner&utm_campaign=cannabissamen\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Cannabissamen Holy Hemp\" title=\"Werbebanner-Weedo-HolyHemp\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-Weedo-HolyHemp.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-65\" data-title=\"Slide\" data-link=\"\/\/www.amazon.de\/gp\/product\/B07HQWG568\/ref=as_li_qf_asin_il_tl?ie=UTF8&tag=weedo07-21&creative=6742&linkCode=as2&creativeASIN=B07HQWG568&linkId=5bbf54f3427e777eaa21fab0d97897b8\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Werbebanner-phenopen\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-phenopen.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-110\" data-title=\"Slide\" data-link=\"\/\/hempcrew.de\/produkte\/cbd-oele\/?utm_source=weedomagazin&utm_medium=slider&utm_campaign=cbdoele\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Werbebanner-CBD-\u00d6le\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-CBD-Oele.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-120\" data-title=\"Slide\" data-link=\"\/\/www.myweedo.de\/dutch-harvest\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"werbebanner-durch-harvest\" width=\"1240\" height=\"600\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/werbebanner-durch-harvest.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-157\" data-title=\"Slide\" data-link=\"\/\/happybuds.de\/cbd-vape-pens\/?utm_source=weedomagazin&utm_medium=banner&utm_campaign=cbdvapes\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Werbebanner-CBD-Vapes\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-CBD-Vapes.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_12_2',rl:[1240,1024,778,480],el:[600],gw:[1240],gh:[600],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider122\"]!==undefined) {window.RS_MODULES.modules[\"revslider122\"].once = false;window.revapi12 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<p>    <\/p>\n\n\n\n<h2><strong>Legalisierung von Cannabis<\/strong><\/h2>\n\n\n\n<p>Cannabis bleibt weiterhin die am h\u00e4ufigsten konsumierte illegale Droge der Erwachsenen, Jugendlichen und jungen Erwachsenen in Deutschland.&nbsp;19 Prozent der Jugendlichen und 42,5 Prozent der jungen Erwachsenen haben laut eigener Angabe bereits Cannabis konsumiert. Die&nbsp;<a href=\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/neue-drogenbeauftragte-daniela-ludwig-csu\/\">Drogenbeautftragte Ludwig<\/a> m\u00f6chte im Hinblick auf eine&nbsp;<a href=\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/cdu-csu-befuerworten-legalisierung-cannabis\/\">Legalisierung<\/a> offen sein, bringt allerdings&nbsp;aufgrund von&nbsp;<a href=\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/immer-weitere-teile-der-union-befuerworten-eine-regulierung-von-cannabis-zum-freizeitkonsum\/\">Uneinigkeiten<\/a> in der eigenen Partei keine Versprechen.<\/p>\n\n\n\n<h2><strong>Weitere illegale Substanzen\/Drogen<\/strong><\/h2>\n\n\n\n<p>Auch der Konsum weiterer illegaler Drogen, beispielsweise Heroin oder Kokain, ist gesunken. Allerdings blieb die Todesrate im vergangenen Jahr mit einer Zahl von 1.276 fast konstant, als Hauptursache wird die Vergiftung durch Opioide genannt.In Berlin wird momentan \u00fcber die M\u00f6glichkeit eines Eigenbedarfs f\u00fcr harte Drogen debattiert. Dies wirft allerdings einen Schein von Harmlosigkeit, obwohl bereits eine kleine Menge mancher Substanzen beim erstmaligen Konsum t\u00f6dlich sein kann. \u201eSelbst wenn die Zahlen der j\u00e4hrlich an illegalen Substanzen Verstorbenen seit einigen Jahren fast gleich bleiben, will ich hier noch einmal klar sagen: Zentral ist, was die Gesundheit der Menschen sch\u00fctzt! Eigenbedarf bei harten Drogen wie Kokain oder Heroin kommt daher absolut nicht in Frage!\u201c Wichtig sind f\u00fcr Ludwig die Hilfsangebote f\u00fcr Suchtkranke: \u201eSuchtkranke d\u00fcrfen nicht vergessen werden! Drogenpolitik hei\u00dft Gesundheitspolitik \u2013 und zwar f\u00fcr alle!\u201c<\/p>\n\n\n\n\n\t\t\t<!-- START Artikel2 REVOLUTION SLIDER 6.5.6 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_11_3_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:20;margin-bottom:20;max-width:;\">\n\t\t\t\t<rs-module id=\"rev_slider_11_3\" style=\"\" data-version=\"6.5.6\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-173\" data-title=\"Slide\" data-link=\"\/\/holy-hemp.de?utm_source=weedomagazin&utm_medium=banner&utm_campaign=cannabissamen\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Cannabissamen Holy Hemp\" title=\"Werbebanner-Weedo-HolyHemp\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-Weedo-HolyHemp.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-55\" data-title=\"Slide\" data-link=\"\/\/happybuds.de?utm_source=weedomagazin&utm_medium=banner&utm_campaign=happybuds\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Werbebanner-HappyBuds\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-HappyBuds.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-121\" data-title=\"Slide\" data-link=\"\/\/www.myweedo.de\/weithalsdose-aus-violettglas-miron\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"werbebanner-miron\" width=\"1240\" height=\"600\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/werbebanner-miron.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-156\" data-title=\"Slide\" data-link=\"\/\/happybuds.de\/cbd-vape-pens\/?utm_source=weedomagazin&utm_medium=banner&utm_campaign=cbdvapes\" data-target=\"_self\" data-seoz=\"front\" data-duration=\"5000ms\" data-anim=\"ms:300;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" title=\"Werbebanner-CBD-Vapes\" width=\"1024\" height=\"495\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2017\/12\/Werbebanner-CBD-Vapes.jpg\" data-parallax=\"off\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_11_3',rl:[1240,1024,778,480],el:[600],gw:[1240],gh:[600],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider113\"]!==undefined) {window.RS_MODULES.modules[\"revslider113\"].once = false;window.revapi11 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n\n\n\n<p>Titelbild \u00a9 vegefox.com \u2013 stock.adobe.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin: Vergangenen&nbsp;Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung,&nbsp;Daniela Ludwig (CSU), den&nbsp;Drogen- und Suchtbericht 2019 vor. Der Bericht bietet einen \u00dcberblick \u00fcber aktuelle Statistiken und Trends im Zusammenhang mit dem Konsum von legalen sowie illegalen Drogen innerhalb Deutschlands. Neben Cannabis, Alkohol und Tabak erscheint auch eine unerwartete neue Sucht, von der immer mehr Jugendliche betroffen sind. [&hellip;]<\/p>\n","protected":false},"author":5683,"featured_media":19248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[233],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.7 (Yoast SEO v19.14) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiter an - Weedo<\/title>\n<meta name=\"description\" content=\"Berlin: Vergangenen Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung, Daniela Ludwig (CSU), den Drogen- und Suchtbericht 2019 vor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiterhin an\" \/>\n<meta property=\"og:description\" content=\"Berlin: Vergangenen Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung, Daniela Ludwig (CSU), den Drogen- und Suchtbericht 2019 vor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/\" \/>\n<meta property=\"og:site_name\" content=\"Weedo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/myweedo\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-11T10:33:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-11T12:52:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2019\/11\/suchtbericht.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Janin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@myweedo\" \/>\n<meta name=\"twitter:site\" content=\"@myweedo\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Janin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/\",\"url\":\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/\",\"name\":\"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiter an - Weedo\",\"isPartOf\":{\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/#website\"},\"datePublished\":\"2019-11-11T10:33:07+00:00\",\"dateModified\":\"2019-11-11T12:52:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/#\/schema\/person\/428a932464a56f2749cf594fa632b6bb\"},\"description\":\"Berlin: Vergangenen Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung, Daniela Ludwig (CSU), den Drogen- und Suchtbericht 2019 vor.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.myweedo.de\/gruene-seiten\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiterhin an\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/#website\",\"url\":\"https:\/\/www.myweedo.de\/gruene-seiten\/\",\"name\":\"Weedo\",\"description\":\"Cannabis Lifestyle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.myweedo.de\/gruene-seiten\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/#\/schema\/person\/428a932464a56f2749cf594fa632b6bb\",\"name\":\"Janin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.myweedo.de\/gruene-seiten\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ebdfc9d53745d16619fc08ea36021445?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ebdfc9d53745d16619fc08ea36021445?s=96&d=mm&r=g\",\"caption\":\"Janin\"},\"url\":\"https:\/\/www.myweedo.de\/gruene-seiten\/author\/janin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiter an - Weedo","description":"Berlin: Vergangenen Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung, Daniela Ludwig (CSU), den Drogen- und Suchtbericht 2019 vor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/","og_locale":"de_DE","og_type":"article","og_title":"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiterhin an","og_description":"Berlin: Vergangenen Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung, Daniela Ludwig (CSU), den Drogen- und Suchtbericht 2019 vor.","og_url":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/","og_site_name":"Weedo","article_publisher":"https:\/\/www.facebook.com\/myweedo\/","article_published_time":"2019-11-11T10:33:07+00:00","article_modified_time":"2019-11-11T12:52:04+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-content\/uploads\/2019\/11\/suchtbericht.jpg","type":"image\/jpeg"}],"author":"Janin","twitter_card":"summary_large_image","twitter_creator":"@myweedo","twitter_site":"@myweedo","twitter_misc":{"Verfasst von":"Janin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/","url":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/","name":"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiter an - Weedo","isPartOf":{"@id":"https:\/\/www.myweedo.de\/gruene-seiten\/#website"},"datePublished":"2019-11-11T10:33:07+00:00","dateModified":"2019-11-11T12:52:04+00:00","author":{"@id":"https:\/\/www.myweedo.de\/gruene-seiten\/#\/schema\/person\/428a932464a56f2749cf594fa632b6bb"},"description":"Berlin: Vergangenen Dienstag (05.11.19) stellte die Drogenbeauftragte der Bundesregierung, Daniela Ludwig (CSU), den Drogen- und Suchtbericht 2019 vor.","breadcrumb":{"@id":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.myweedo.de\/gruene-seiten\/politik\/drogen-und-suchtbericht-2019-cannabiskonsum-steigt-weiterhin-an\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.myweedo.de\/gruene-seiten\/"},{"@type":"ListItem","position":2,"name":"Drogen- und Suchtbericht 2019: Cannabiskonsum steigt weiterhin an"}]},{"@type":"WebSite","@id":"https:\/\/www.myweedo.de\/gruene-seiten\/#website","url":"https:\/\/www.myweedo.de\/gruene-seiten\/","name":"Weedo","description":"Cannabis Lifestyle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.myweedo.de\/gruene-seiten\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.myweedo.de\/gruene-seiten\/#\/schema\/person\/428a932464a56f2749cf594fa632b6bb","name":"Janin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.myweedo.de\/gruene-seiten\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ebdfc9d53745d16619fc08ea36021445?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ebdfc9d53745d16619fc08ea36021445?s=96&d=mm&r=g","caption":"Janin"},"url":"https:\/\/www.myweedo.de\/gruene-seiten\/author\/janin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/posts\/19158"}],"collection":[{"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/users\/5683"}],"replies":[{"embeddable":true,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/comments?post=19158"}],"version-history":[{"count":8,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/posts\/19158\/revisions"}],"predecessor-version":[{"id":19256,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/posts\/19158\/revisions\/19256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/media\/19248"}],"wp:attachment":[{"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/media?parent=19158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/categories?post=19158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.myweedo.de\/gruene-seiten\/wp-json\/wp\/v2\/tags?post=19158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}